{"id":108456,"date":"2025-11-19T17:16:39","date_gmt":"2025-11-19T16:16:39","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/bestemmingen-hautes-alpes\/reallon-crevoux\/"},"modified":"2026-06-19T12:11:09","modified_gmt":"2026-06-19T10:11:09","slug":"reallon-crevoux","status":"publish","type":"page","link":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/","title":{"rendered":"R\u00e9allon | Cr\u00e9voux"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull hero-banner-cover-wide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"yoast-breadcrumbs\"><span><span><a href=\"https:\/\/www.hautes-alpes.net\/nl\/hautes-alpes\/\">Accueil<\/a><\/span>  <span><a href=\"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/\">Bestemmingen - Hautes-Alpes<\/a><\/span>  <span><a href=\"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/\">Bestemmingen - Hautes-Alpes<\/a><\/span>  <span class=\"breadcrumb_last\" aria-current=\"page\">R\u00e9allon | Cr\u00e9voux<\/span><\/span><\/div>\n\n\n<h1 class=\"wp-block-ws-library-post-title\">R\u00e9allon | Cr\u00e9voux<\/h1>\n\n\n\n<div class=\"wp-block-ws-library-media-embed ws-media-embed\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/230224105224-re-mi-morel-ot-serre-ponc-on-1-scaled-2000x1000.jpg\" alt=\"\" class=\"ws-media-embed__image\" style=\"aspect-ratio:2000\/1000\"><\/div>\n\n\n\n<p class=\"subtitle wp-block-paragraph\">R\u00e9allon | Cr\u00e9voux<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier zijn <strong>twee discrete juweeltjes<\/strong>, twee resortdorpen die authenticiteit verkiezen boven glitter. <strong>Cr\u00e9voux en R\u00e9allon, hoog boven het meer van <a href=\"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/serre-poncon\/\">Serre-Pon\u00e7on<\/a><\/strong>, bieden echt, rauw ski\u00ebn, waar je de essentie van <a href=\"https:\/\/www.hautes-alpes.net\/nl\/ervaringen-hautes-alpes\/ski\/\">ski\u00ebn<\/a> kunt herontdekken. Geen drukte, geen lange wachtrijen, gewoon pure sensaties, net als op de eerste dag. <\/p>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group alignfull step-by-step has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-columns alignwide has-2-columns are-vertically-aligned-center layout-5050\">\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<h2 class=\"wp-block-heading\"><strong>Cr\u00e9voux<\/strong><br\/>de wilde versie van ski\u00ebn<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In <strong>Cr\u00e9voux<\/strong> zweef je <strong>door de lariksbomen<\/strong> als op een oude ansichtkaart. Er zijn hier <strong>geen<\/strong> ultramoderne stoeltjesliften en je moet je helemaal optrekken. En dat is maar goed ook. De sfeer is eenvoudig, ruig, een echt poederreservaat waar liefhebbers van off-piste komen voor het natuurlijke, het wilde. Er is geen behoefte aan glitter als de sneeuw zo gul is.    <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<div class=\"wp-block-ws-library-ws-image\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/230224093659-re-mi-morel-ot-serre-ponc-on-2-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-56607\"><div class=\"credits\">R. Morel<\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-columns alignwide has-2-columns are-vertically-aligned-center layout-5050\">\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<h2 class=\"wp-block-heading\"><strong>Reallon<\/strong><br\/>het uitzicht als een partner in het spel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e9allon<\/strong> is het <strong>balkon van <a href=\"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/serre-poncon\/\">Serre-Pon\u00e7on<\/a><\/strong>. Ski\u00ebn met uitzicht op het meer, met de <strong>Aiguilles de Chabri\u00e8res<\/strong> op de achtergrond, is een luxe die geen enkel ander skigebied biedt. Het is een geweldige manier om plezier te hebben in een skioord op menselijke schaal. En om het plezier te verlengen, zorgt de <strong>Ripaaa <\/strong>voor een adrenalinestoot: rodelen in de winter, bergkarten in de zomer, het is de helling waar volwassenen weer kinderen worden.   <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<div class=\"wp-block-ws-library-ws-image\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/shooting-photos-reallon-2022-23-fabien-thibault-5-2-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-53682\"><div class=\"credits\">F. Thibault<\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-columns alignwide has-2-columns are-vertically-aligned-center layout-5050\">\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<h2 class=\"wp-block-heading\"><strong>Versie<\/strong><br\/>zomer<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Als de sneeuw zich terugtrekt, verandert het terrein van discipline. De paden openen zich voor <strong><a href=\"https:\/\/www.hautes-alpes.net\/nl\/ervaringen-hautes-alpes\/wandelingen\/\">trail<\/a><\/strong>trail <strong><a href=\"https:\/\/www.hautes-alpes.net\/nl\/ervaringen-hautes-alpes\/mountainbike\/\">mountainbikers<\/a><\/strong>en gezinnen op uitstapjes. Elke bocht, elke bergkam, wordt een racelijn, een moeiteloze klim, een opwindende afdaling. De zomer in <strong>R\u00e9allon <\/strong>en <strong>Cr\u00e9voux<\/strong> is altijd een moment van plezier: tempo houden, fit blijven, ademhalen in de bergen.   <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<div class=\"wp-block-ws-library-ws-image\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/remi-morel-outdoormix-festival-5-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-56504\"><div class=\"credits\">R. Morel<\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading is-style-title-1\">Hoogtepunten van <strong>R\u00e9allon en Cr\u00e9voux<\/strong><\/h2>\n\n<div class=\"wp-block-group alignwide list-nodetails is-content-justification-center is-layout-flex wp-container-core-group-is-layout-9e779cc1 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-image is-style-simple\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/04\/110724145115-office-de-tourisme-de-serre-poncon2-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-492802\"><div class=\"credits\">Het Kids au Sommet festival georganiseerd door het R\u00e9allon resort.<\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Festival<\/em><strong>Festival Kinderen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In R\u00e9allon verandert het Festival Kids au Sommet het skioord in een avonturenparadijs voor gezinnen: voorstellingen, workshops en activiteiten op grote hoogte brengen de bergen en de verbeelding tot leven tijdens een speels en feestelijk evenement in het hart van de Hautes-Alpes.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-image is-style-simple\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/04\/rellon-trophee-enduro-des-alpes-1-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-492798\"><div class=\"credits\"><\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><em>MOUNTAINBIKEN<br\/><\/em><strong>Alpen Enduro Trofee<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Adrenaline gegarandeerd bij de Troph\u00e9e Enduro des Alpes in R\u00e9allon: een niet te missen enduro mountainbike-evenement waar ervaren rijders over technische paden razen met uitzicht op het meer van Serre-Pon\u00e7on.<\/p>\n<\/div>\n<\/div>\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading is-style-title-1\"><strong>Praktisch<\/strong> notitieboek<\/h2>\n\n<div class=\"wp-block-ws-library-ws-tabs alignfull\"><ul class=\"tabs-titles\"><li class=\"tab-title is-active\" data-tab-index=\"0\">Kaart<\/li><li class=\"tab-title\" data-tab-index=\"1\">Webcam<\/li><li class=\"tab-title\" data-tab-index=\"2\">Sneeuwbulletin<\/li><li class=\"tab-title\" data-tab-index=\"3\">Accommodatie  <\/li><\/ul><div class=\"tabs-list\">\n<div class=\"wp-block-ws-library-ws-tab\" style=\"display:none\"><p class=\"tab-title\">Kaart<\/p><div class=\"tab-content\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-002ffff5 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-ws-library-ws-image tab-group-media\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/reallon-plan-des-pistes-2025-2026-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-82469\"><div class=\"credits\"><\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-image\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/crevoux-plan-des-pistes-2025-2026-page-0001-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-82465\"><div class=\"credits\"><\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-002ffff5 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/reallon-plan-des-pistes-2025-2026.jpg\">Download de kaart van R\u00e9allon<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/crevoux-plan-des-pistes-2025-2026-page-0001-scaled.jpg\">Download de kaart van Cr\u00e9voux<\/a><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-tab\" style=\"display:none\"><p class=\"tab-title\">Webcam<\/p><div class=\"tab-content\">\n<div class=\"wp-block-group tab-row is-nowrap is-layout-flex wp-container-core-group-is-layout-002ffff5 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group tab-group-content is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"is-style-highlighted wp-block-paragraph\">Volg het weer, de sneeuwcondities en de activiteit op de pistes om je dag in de bergen te plannen!<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-webcam has-ws-lightbox\" aria-haspopup=\"dialog\" role=\"button\" aria-expanded=\"false\" aria-label=\"R\u00e9allon \u2013 Chabri\u00e8res\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"77692\" href=\"#\"><a class=\"wp-block-button__link wp-element-button has-ws-lightbox\" href=\"#\" role=\"button\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"77692\" data-ws-lightbox-snippet=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LnNraWluZm8ubmwvbGFjLXNlcnJlLXBvbmNvbi9yZWFsbG9uL2NoYWJyaWVyZXMiIHdpZHRoPSIxMDAlIiBoZWlnaHQ9IjQ1MCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj48L2lmcmFtZT4=\">\u25b6 ZIE DE REALLON Webcam<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-webcam has-ws-lightbox\" aria-haspopup=\"dialog\" role=\"button\" aria-expanded=\"false\" aria-label=\"Cr\u00e9voux \u2013 Front de neige\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"80485\" href=\"#\"><a class=\"wp-block-button__link wp-element-button has-ws-lightbox\" href=\"#\" role=\"button\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"80485\" data-ws-lightbox-snippet=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LnNraWluZm8ubmwvY3Jldm91eC9mcm9udC1kZS1uZWlnZSIgd2lkdGg9IjEwMCUiIGhlaWdodD0iNDUwIiBmcmFtZWJvcmRlcj0iMCIgYWxsb3dmdWxsc2NyZWVuPjwvaWZyYW1lPg==\">\u25b6 BEKIJK DE Webcam VAN cr\u00e9voux<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-tab\" style=\"display:none\"><p class=\"tab-title\">Sneeuwbulletin<\/p><div class=\"tab-content\">\n<div class=\"wp-block-group tab-row is-nowrap is-layout-flex wp-container-core-group-is-layout-002ffff5 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group tab-group-content is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"is-style-highlighted wp-block-paragraph\">Bekijk alle sneeuwcondities in de resorts :<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-snow has-ws-lightbox\" aria-haspopup=\"dialog\" role=\"button\" aria-expanded=\"false\" aria-label=\"BULLETIN NEIGE \u2013 Crevoux\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"82899\" href=\"#\"><a class=\"wp-block-button__link wp-element-button has-ws-lightbox\" href=\"#\" role=\"button\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"82899\" data-ws-lightbox-snippet=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LnNraWluZm8ubmwvd2lkZ2V0L3Nub3c\/cmVzb3J0PTIxNjEiIHdpZHRoPSIxMDAlIiBoZWlnaHQ9IjQ1MCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj48L2lmcmFtZT4=\">sneeuwbericht cr\u00e9voux<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-snow has-ws-lightbox\" aria-haspopup=\"dialog\" role=\"button\" aria-expanded=\"false\" aria-label=\"BULLETIN NEIGE \u2013 Reallon\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"82900\" href=\"#\"><a class=\"wp-block-button__link wp-element-button has-ws-lightbox\" href=\"#\" role=\"button\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"82900\" data-ws-lightbox-snippet=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LnNraWluZm8ubmwvd2lkZ2V0L3Nub3c\/cmVzb3J0PTE3OTYiIHdpZHRoPSIxMDAlIiBoZWlnaHQ9IjQ1MCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj48L2lmcmFtZT4=\">Sneeuwbulletin<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-tab\" style=\"display:none\"><p class=\"tab-title\">Accommodatie  <\/p><div class=\"tab-content\">\n<div class=\"wp-block-group tab-row is-nowrap is-layout-flex wp-container-core-group-is-layout-002ffff5 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group tab-group-content is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"is-style-highlighted wp-block-paragraph\">Op zoek naar een vakantie in R\u00e9allon of Cr\u00e9voux? Vind je accommodatie en alle diensten die je nodig hebt. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-image tab-group-media\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.hautes-alpes.net\/nl\/organiseren\/gemeubileerde-accommodatie-gites\/?_station=reallon-crevoux\">Bekijk de accommodatie<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Advies nodig?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Het toeristenbureau,<br\/><strong>uw plaatselijke bondgenoot<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Goede tips, idee\u00ebn voor activiteiten, persoonlijk advies: <\/strong>aarzel niet om <strong>de teams<\/strong> van het Office du Tourisme te ontmoeten of contact met ze op te nemen om het beste uit je bestemming te halen.<\/p>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">Serre-Pon\u00e7on<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">9 AV. de la Combe d&#8217;Or, 05160 Savines-le-Lac<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><a href=\"tel:+33492443100\">04 92 44 31 00<\/a><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill is-style-default\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/www.serreponcon.com\">Kantoor website<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-default\"\/>\n\n<h2 class=\"wp-block-heading is-style-title-1\"><strong>Zie ook<\/strong><\/h2>\n\n<div class=\"wp-block-group alignwide list-nodetails is-content-justification-center is-layout-flex wp-container-core-group-is-layout-c9a5442e wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-image is-style-simple\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/serre-poncon-28-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-53667\"><div class=\"credits\">Toeristenbureau Serre-Pon\u00e7on<\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-title-2\"><em>Bestemmingen<br\/><\/em>Serre-Pon\u00e7on<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/serre-poncon\/\">Zie<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-image is-style-simple\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/ski-neige-fraiche-serre-che-6-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-60640\"><div class=\"credits\">T. Blais<\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-title-2\"><em>ErvaringenSki\u00ebn<\/em><\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.hautes-alpes.net\/nl\/ervaringen-hautes-alpes\/ski\/\">Zie<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-ws-library-ws-share\"><span class=\"share-subtitle\">Vond je deze pagina leuk?<\/span><span class=\"share-title\">Deel het!<\/span><button class=\"ws-share-button wp-element-button\">Deel deze pagina<\/button><\/div>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9allon | Cr\u00e9voux Hier zijn twee discrete juweeltjes, twee resortdorpen die authenticiteit verkiezen boven glitter. Cr\u00e9voux en R\u00e9allon, hoog boven [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":107624,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"is_dark_mode":false,"footnotes":""},"page_label":[],"class_list":["post-108456","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9allon | Cr\u00e9voux - Hautes-Alpes<\/title>\n<meta name=\"description\" content=\"R\u00e9allon | Cr\u00e9voux R\u00e9allon | Cr\u00e9voux Hier zijn twee discrete juweeltjes, twee resortdorpen die authenticiteit verkiezen boven glitter. Cr\u00e9voux en R\u00e9allon,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9allon | Cr\u00e9voux - Hautes-Alpes\" \/>\n<meta property=\"og:description\" content=\"R\u00e9allon | Cr\u00e9voux R\u00e9allon | Cr\u00e9voux Hier zijn twee discrete juweeltjes, twee resortdorpen die authenticiteit verkiezen boven glitter. Cr\u00e9voux en R\u00e9allon,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-19T10:11:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/230224105224-re-mi-morel-ot-serre-ponc-on-1-scaled-2000x1000.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/reallon-crevoux\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/reallon-crevoux\\\/\",\"name\":\"R\u00e9allon | Cr\u00e9voux - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/reallon-crevoux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/reallon-crevoux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/230224105224-re-mi-morel-ot-serre-ponc-on-1-scaled-2000x1000.jpg\",\"datePublished\":\"2025-11-19T16:16:39+00:00\",\"dateModified\":\"2026-06-19T10:11:09+00:00\",\"description\":\"R\u00e9allon | Cr\u00e9voux R\u00e9allon | Cr\u00e9voux Hier zijn twee discrete juweeltjes, twee resortdorpen die authenticiteit verkiezen boven glitter. Cr\u00e9voux en R\u00e9allon,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/reallon-crevoux\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/reallon-crevoux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/reallon-crevoux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/230224105224-re-mi-morel-ot-serre-ponc-on-1-scaled-2000x1000.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/230224105224-re-mi-morel-ot-serre-ponc-on-1-scaled-2000x1000.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/reallon-crevoux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bestemmingen - Hautes-Alpes\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bestemmingen - Hautes-Alpes\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/bestemmingen-hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"R\u00e9allon | Cr\u00e9voux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9allon | Cr\u00e9voux - Hautes-Alpes","description":"R\u00e9allon | Cr\u00e9voux R\u00e9allon | Cr\u00e9voux Hier zijn twee discrete juweeltjes, twee resortdorpen die authenticiteit verkiezen boven glitter. Cr\u00e9voux en R\u00e9allon,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/","og_locale":"nl_NL","og_type":"article","og_title":"R\u00e9allon | Cr\u00e9voux - Hautes-Alpes","og_description":"R\u00e9allon | Cr\u00e9voux R\u00e9allon | Cr\u00e9voux Hier zijn twee discrete juweeltjes, twee resortdorpen die authenticiteit verkiezen boven glitter. Cr\u00e9voux en R\u00e9allon,","og_url":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/","og_site_name":"Hautes-Alpes","article_modified_time":"2026-06-19T10:11:09+00:00","og_image":[{"url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/230224105224-re-mi-morel-ot-serre-ponc-on-1-scaled-2000x1000.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"3 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/","url":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/","name":"R\u00e9allon | Cr\u00e9voux - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/#primaryimage"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/230224105224-re-mi-morel-ot-serre-ponc-on-1-scaled-2000x1000.jpg","datePublished":"2025-11-19T16:16:39+00:00","dateModified":"2026-06-19T10:11:09+00:00","description":"R\u00e9allon | Cr\u00e9voux R\u00e9allon | Cr\u00e9voux Hier zijn twee discrete juweeltjes, twee resortdorpen die authenticiteit verkiezen boven glitter. Cr\u00e9voux en R\u00e9allon,","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/#primaryimage","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/230224105224-re-mi-morel-ot-serre-ponc-on-1-scaled-2000x1000.jpg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/230224105224-re-mi-morel-ot-serre-ponc-on-1-scaled-2000x1000.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/reallon-crevoux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/nl\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Bestemmingen - Hautes-Alpes","item":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/"},{"@type":"ListItem","position":3,"name":"Bestemmingen - Hautes-Alpes","item":"https:\/\/www.hautes-alpes.net\/nl\/bestemmingen-hautes-alpes\/"},{"@type":"ListItem","position":4,"name":"R\u00e9allon | Cr\u00e9voux"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/nl\/#website","url":"https:\/\/www.hautes-alpes.net\/nl\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/nl\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.hautes-alpes.net\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/pages\/108456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/comments?post=108456"}],"version-history":[{"count":10,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/pages\/108456\/revisions"}],"predecessor-version":[{"id":615362,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/pages\/108456\/revisions\/615362"}],"up":[{"embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/pages\/107624"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/media?parent=108456"}],"wp:term":[{"taxonomy":"page_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/page_label?post=108456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}