{"id":556651,"date":"2026-06-01T21:38:35","date_gmt":"2026-06-01T19:38:35","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/les-terrasses-du-paradis-6\/"},"modified":"2026-06-01T21:38:35","modified_gmt":"2026-06-01T19:38:35","slug":"les-terrasses-du-paradis-6","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/","title":{"rendered":"Les Terrasses du Paradis"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"419118"},"apidae-selections":[7897],"apidae-environnements":[359,339,1553,351,335],"apidae-chaines":[],"apidae-communes":[4378],"apidae-modes_paiement":[171,163,189,185],"apidae-services":[1314,253,1471,249],"apidae-natures_terrain":[],"apidae-distinctions":[],"apidae-langues_parlees":[1406,198,202],"apidae-equipements":[517,1271,1247,3223,468,735,721,2455],"apidae-equipements_activite":[],"apidae-conforts":[590,569,565,560,582,887,1476,3258,3248,2728,2140,882,594,586,3278],"apidae-activites":[],"apidae-tourismes_adaptes":[],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[603,840,611,1583,607],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[],"apidae-criteres_internes":[],"apidae-territoires":[420,2948,416,1706,404,2958,2993,2630,2620,2943,408,2615,2953,2938],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[368,380,376,372],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[3756],"apidae-tourisme_affaire":[456],"class_list":["post-556651","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Terrasses du Paradis - Hautes-Alpes<\/title>\n<meta name=\"description\" content=\"Aan de voet van de klimrotsen, wordt u welkom geheten door M\u00e9linda et Florent. De B&amp;B beschikt over 3 ruime kamers, voor 2 tot 4 personen in een nieuw, op het Zuiden gebouwd, huis. Prachtig uitzicht. Het ontbijt wordt geserveerd op het terras of in de eetzaal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Terrasses du Paradis - Hautes-Alpes\" \/>\n<meta property=\"og:description\" content=\"Aan de voet van de klimrotsen, wordt u welkom geheten door M\u00e9linda et Florent. De B&amp;B beschikt over 3 ruime kamers, voor 2 tot 4 personen in een nieuw, op het Zuiden gebouwd, huis. Prachtig uitzicht. Het ontbijt wordt geserveerd op het terras of in de eetzaal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/les-terrasses-du-paradis-6\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/les-terrasses-du-paradis-6\\\/\",\"name\":\"Les Terrasses du Paradis - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#website\"},\"datePublished\":\"2026-06-01T19:38:35+00:00\",\"description\":\"Aan de voet van de klimrotsen, wordt u welkom geheten door M\u00e9linda et Florent. De B&B beschikt over 3 ruime kamers, voor 2 tot 4 personen in een nieuw, op het Zuiden gebouwd, huis. Prachtig uitzicht. Het ontbijt wordt geserveerd op het terras of in de eetzaal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/les-terrasses-du-paradis-6\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/les-terrasses-du-paradis-6\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/les-terrasses-du-paradis-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Terrasses du Paradis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Terrasses du Paradis - Hautes-Alpes","description":"Aan de voet van de klimrotsen, wordt u welkom geheten door M\u00e9linda et Florent. De B&B beschikt over 3 ruime kamers, voor 2 tot 4 personen in een nieuw, op het Zuiden gebouwd, huis. Prachtig uitzicht. Het ontbijt wordt geserveerd op het terras of in de eetzaal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/","og_locale":"nl_NL","og_type":"article","og_title":"Les Terrasses du Paradis - Hautes-Alpes","og_description":"Aan de voet van de klimrotsen, wordt u welkom geheten door M\u00e9linda et Florent. De B&B beschikt over 3 ruime kamers, voor 2 tot 4 personen in een nieuw, op het Zuiden gebouwd, huis. Prachtig uitzicht. Het ontbijt wordt geserveerd op het terras of in de eetzaal.","og_url":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/","og_site_name":"Hautes-Alpes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/","url":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/","name":"Les Terrasses du Paradis - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/#website"},"datePublished":"2026-06-01T19:38:35+00:00","description":"Aan de voet van de klimrotsen, wordt u welkom geheten door M\u00e9linda et Florent. De B&B beschikt over 3 ruime kamers, voor 2 tot 4 personen in een nieuw, op het Zuiden gebouwd, huis. Prachtig uitzicht. Het ontbijt wordt geserveerd op het terras of in de eetzaal.","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/les-terrasses-du-paradis-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/nl\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Les Terrasses du Paradis"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/nl\/#website","url":"https:\/\/www.hautes-alpes.net\/nl\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/nl\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.hautes-alpes.net\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae\/556651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/media?parent=556651"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-selections?post=556651"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-environnements?post=556651"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-chaines?post=556651"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-communes?post=556651"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-modes_paiement?post=556651"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-services?post=556651"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-natures_terrain?post=556651"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-distinctions?post=556651"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-langues_parlees?post=556651"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-equipements?post=556651"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-equipements_activite?post=556651"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-conforts?post=556651"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-activites?post=556651"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=556651"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=556651"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_clientele?post=556651"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=556651"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=556651"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-activites_sportives?post=556651"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=556651"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=556651"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=556651"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-criteres_internes?post=556651"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-territoires?post=556651"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=556651"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-salles_equipement?post=556651"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=556651"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-salles_restauration?post=556651"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-categories?post=556651"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-specialites?post=556651"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-indications_periode?post=556651"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_label?post=556651"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-hotel_classement?post=556651"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_hebergement?post=556651"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=556651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}