{"id":522478,"date":"2026-05-13T03:02:42","date_gmt":"2026-05-13T01:02:42","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/region-sud-european-cups-heren-alpineskien\/"},"modified":"2026-05-13T03:04:06","modified_gmt":"2026-05-13T01:04:06","slug":"region-sud-european-cups-heren-alpineskien-2","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/","title":{"rendered":"Regionale Europese bekers Zuid - Mannen (Alpineski\u00ebn)"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"5332624"},"apidae-selections":[7792,8643],"apidae-environnements":[],"apidae-chaines":[],"apidae-communes":[2838],"apidae-modes_paiement":[],"apidae-services":[],"apidae-natures_terrain":[],"apidae-distinctions":[],"apidae-langues_parlees":[202],"apidae-equipements":[],"apidae-equipements_activite":[],"apidae-conforts":[],"apidae-activites":[],"apidae-tourismes_adaptes":[],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[5027],"apidae-criteres_internes":[5022],"apidae-territoires":[420,973,2768,2773,416,404,2843,396,408,1701],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[376],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[],"apidae-tourisme_affaire":[],"class_list":["post-522478","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regionale Europese bekers Zuid - Mannen (Alpineski\u00ebn) - Hautes-Alpes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regionale Europese bekers Zuid - Mannen (Alpineski\u00ebn) - Hautes-Alpes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:04:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/region-sud-european-cups-heren-alpineskien-2\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/region-sud-european-cups-heren-alpineskien-2\\\/\",\"name\":\"Regionale Europese bekers Zuid - Mannen (Alpineski\u00ebn) - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#website\"},\"datePublished\":\"2026-05-13T01:02:42+00:00\",\"dateModified\":\"2026-05-13T01:04:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/region-sud-european-cups-heren-alpineskien-2\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/region-sud-european-cups-heren-alpineskien-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/fiche\\\/region-sud-european-cups-heren-alpineskien-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regionale Europese bekers Zuid - Mannen (Alpineski\u00ebn)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regionale Europese bekers Zuid - Mannen (Alpineski\u00ebn) - Hautes-Alpes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/","og_locale":"nl_NL","og_type":"article","og_title":"Regionale Europese bekers Zuid - Mannen (Alpineski\u00ebn) - Hautes-Alpes","og_url":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/","og_site_name":"Hautes-Alpes","article_modified_time":"2026-05-13T01:04:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/","url":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/","name":"Regionale Europese bekers Zuid - Mannen (Alpineski\u00ebn) - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/#website"},"datePublished":"2026-05-13T01:02:42+00:00","dateModified":"2026-05-13T01:04:06+00:00","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/nl\/fiche\/region-sud-european-cups-heren-alpineskien-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/nl\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Regionale Europese bekers Zuid - Mannen (Alpineski\u00ebn)"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/nl\/#website","url":"https:\/\/www.hautes-alpes.net\/nl\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/nl\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.hautes-alpes.net\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae\/522478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/media?parent=522478"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-selections?post=522478"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-environnements?post=522478"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-chaines?post=522478"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-communes?post=522478"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-modes_paiement?post=522478"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-services?post=522478"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-natures_terrain?post=522478"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-distinctions?post=522478"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-langues_parlees?post=522478"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-equipements?post=522478"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-equipements_activite?post=522478"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-conforts?post=522478"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-activites?post=522478"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=522478"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=522478"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_clientele?post=522478"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=522478"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=522478"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-activites_sportives?post=522478"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=522478"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=522478"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=522478"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-criteres_internes?post=522478"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-territoires?post=522478"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=522478"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-salles_equipement?post=522478"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=522478"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-salles_restauration?post=522478"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-categories?post=522478"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-specialites?post=522478"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-indications_periode?post=522478"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_label?post=522478"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-hotel_classement?post=522478"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-types_hebergement?post=522478"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/nl\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=522478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}