{"id":108316,"date":"2025-11-19T16:40:35","date_gmt":"2025-11-19T15:40:35","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/destinazioni-hautes-alpes\/les-orres\/"},"modified":"2026-06-22T10:22:10","modified_gmt":"2026-06-22T08:22:10","slug":"les-orres","status":"publish","type":"page","link":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/","title":{"rendered":"Les Orres"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull hero-banner-cover-wide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"yoast-breadcrumbs\"><span><span><a href=\"https:\/\/www.hautes-alpes.net\/it\/hautes-alpes\/\">Accueil<\/a><\/span>  <span><a href=\"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/\">Destinazioni - Hautes-Alpes<\/a><\/span>  <span><a href=\"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/\">Destinazioni - Hautes-Alpes<\/a><\/span>  <span class=\"breadcrumb_last\" aria-current=\"page\">Les Orres<\/span><\/span><\/div>\n\n\n<h1 class=\"wp-block-ws-library-post-title\">Les Orres<\/h1>\n\n\n\n<div class=\"wp-block-ws-library-media-embed ws-media-embed\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/itinera-magica-les-orres-24-2000x1000.jpg\" alt=\"\" class=\"ws-media-embed__image\" style=\"aspect-ratio:2000\/1000\"><\/div>\n\n\n\n<p class=\"subtitle wp-block-paragraph\">La montagna di domani<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arroccato sopra il lago di <a href=\"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/serre-poncon\/\">Serre-Pon\u00e7on<\/a>, Les Orres<\/strong> \u00e8 un vero e proprio parco giochi a grandezza naturale. Ogni pista \u00e8 un invito a mollare i freni, a cercare la velocit\u00e0, ad assaporare l&#8217;emozione pura di scivolare. E tra una discesa e l&#8217;altra, puoi alzare lo sguardo e respirare l&#8217;aria fresca che fa venire voglia a sciatori ed escursionisti di prolungare il momento.  <\/p>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group alignfull step-by-step has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-columns alignwide has-2-columns are-vertically-aligned-center layout-5050\">\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<h2 class=\"wp-block-heading\"><strong>Un ambiente alpino <br\/><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les Orres ha un&#8217;<strong>atmosfera unica<\/strong>: piste di larici, un <strong>panorama mozzafiato su <a href=\"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/serre-poncon\/\">Serre-Pon\u00e7on<\/a><\/strong> e una <strong>localit\u00e0 all&#8217;avanguardia in termini di sviluppo sostenibile<\/strong>. Gli sport sulla neve sono accompagnati da una coscienza ecologica: produzione di energia verde, mobilit\u00e0 dolce e azioni concrete per preservare un parco giochi caro a tutti. <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<div class=\"wp-block-ws-library-ws-image\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/itinera-magica-les-orres-23-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-55070\"><div class=\"credits\">Itinera Magica<\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-columns alignwide has-2-columns are-vertically-aligned-center layout-5050\">\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<h2 class=\"wp-block-heading\"><strong>Il paradiso della<\/strong>mountain bike <strong> <br\/><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quando la neve lascia il posto ai sentieri, il <strong>bike park<\/strong> di Les Orres prende il sopravvento. Percorsi tecnici, discese veloci e un&#8217;accoglienza calorosa per i ciclisti: ogni anno la localit\u00e0 si afferma come un <strong>luogo imperdibile per la <a href=\"https:\/\/www.hautes-alpes.net\/it\/esperienze-hautes-alpes\/bicicletta-da-montagna\/\">mountain bike <\/a><\/strong>. La prova \u00e8 che ospita regolarmente competizioni di alto livello, che riuniscono appassionati dilettanti e campioni della disciplina.  <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<div class=\"wp-block-ws-library-ws-image\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/bike-park-lesorres-agence-kros-remifabregue-3-sur-22-1-1240x800.jpeg\" alt=\"\" class=\"single_image ws-image-55056\"><div class=\"credits\">R. Fabregue<\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-columns alignwide has-2-columns are-vertically-aligned-center layout-5050\">\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<h2 class=\"wp-block-heading\"><strong><br\/> attrezzature<\/strong>progettate per gli spettacoli<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sebbene il resort sia vivo e vegeto in inverno, non dorme mai veramente. C&#8217;\u00e8 una vertiginosa <strong>zip line<\/strong>, <strong>slittini in quattro stagioni<\/strong> per discese ad alta velocit\u00e0, una vivace <strong>pista di pattinaggio<\/strong> e persino il <strong>PSI (P\u00f4le Sport et Innovation)<\/strong>, un nuovissimo tempio dell&#8217;innovazione digitale e dello sport in realt\u00e0 aumentata. Les Orres sta ampliando la sua gamma di esperienze, confermando il suo status di localit\u00e0 sportiva all&#8217;avanguardia. <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<div class=\"wp-block-ws-library-ws-image\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/psi-ot-les-orres-2-1-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-82920\"><div class=\"credits\"><\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group block-chiffres has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading is-style-title-2\">Les Orres <br\/><strong>in cifre<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stats\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>SOLLEVATORI DI SCI<\/strong><\/td><td>17<\/td><\/tr><tr><td>TRACCE<\/td><td>36<\/td><\/tr><tr><td><strong>KM DESCENT<\/strong><\/td><td>100<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"field-source wp-block-paragraph\"><\/p>\n<\/div>\n\n<div class=\"wp-block-ws-library-ws-gallery ws-gallery alignfull\"><div class=\"group-content\"><div class=\"field-title\">La montagna radiosa<\/div><p class=\"field-text\">impegnati per il domani<\/p><\/div><div class=\"list-images\"><div class=\"item item-media scroll-detect\" data-end-offset=\"30%\"><a href=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5.jpg\" class=\"item-media__link init-lightbox\" data-glightbox=\"ws-gallery\" data-gallery=\"ws-gallery\" data-title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-1024x683.jpg\" alt=\"\" class=\"ws-image wp-image-55055\" srcset=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-1024x683.jpg 1024w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-300x200.jpg 300w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-768x512.jpg 768w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-1536x1025.jpg 1536w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-480x320.jpg 480w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-960x640.jpg 960w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-660x440.jpg 660w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-525x350.jpg 525w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-929x620.jpg 929w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5-959x640.jpg 959w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/belvedere-mont-guillaume-alpesphotographiescom-5.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"item item-media scroll-detect\" data-end-offset=\"30%\"><a href=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-scaled.jpg\" class=\"item-media__link init-lightbox\" data-glightbox=\"ws-gallery\" data-gallery=\"ws-gallery\" data-title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-1024x683.jpg\" alt=\"\" class=\"ws-image wp-image-55064\" srcset=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-1024x683.jpg 1024w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-300x200.jpg 300w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-768x512.jpg 768w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-1536x1024.jpg 1536w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-2048x1365.jpg 2048w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-480x320.jpg 480w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-960x640.jpg 960w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-660x440.jpg 660w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-525x350.jpg 525w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/cosy-1-930x620.jpg 930w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><div class=\"item item-media scroll-detect\" data-end-offset=\"30%\"><a href=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-scaled.jpg\" class=\"item-media__link init-lightbox\" data-glightbox=\"ws-gallery\" data-gallery=\"ws-gallery\" data-title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"632\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-1024x632.jpg\" alt=\"\" class=\"ws-image wp-image-55028\" srcset=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-1024x632.jpg 1024w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-300x185.jpg 300w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-768x474.jpg 768w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-1536x947.jpg 1536w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-2048x1263.jpg 2048w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-480x296.jpg 480w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-960x592.jpg 960w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-1005x620.jpg 1005w, https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/les-orres-agencekros-remifabregue-10-1-1038x640.jpg 1038w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading is-style-title-1\">Punti di forza di <strong>Les Orres<\/strong><\/h2>\n\n<div class=\"wp-block-group alignwide list-nodetails is-content-justification-center is-layout-flex wp-container-core-group-is-layout-c9a5442e wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-image is-style-simple\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/04\/les-orres-girly-ride-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-486202\"><div class=\"credits\"><\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><em>BICICLETTA DA MONTAGNA<br\/><\/em><strong>Giro femminile<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ogni estate, il Girly Ride di Les Orres riunisce le donne in mountain bike per una giornata di sport e di festa. Con percorsi accessibili, workshop tecnici e un&#8217;atmosfera amichevole, \u00e8 un incontro femminile in montagna che fa bene. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-image is-style-simple\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/04\/les-orres-pure-flow-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-486203\"><div class=\"credits\"><\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Festival<br\/><\/em><strong>Festival del benessere e degli sport di montagna - Pure flow<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tra le vette e l\u2019aria di montagna, Festival del benessere e dello sport in montagna - Pure Flow ti invita a respirare, muoverti e ritrovare il tuo equilibrio. Yoga, trail, laboratori olistici: un concentrato di energia alpina per armonizzare corpo e mente nel cuore delle Hautes-Alpes. <\/p>\n<\/div>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-ws-library-ws-animated-quote\"><blockquote class=\"quote-container quote-align-undefined\"><footer><cite class=\"quote-subcontent\"><strong>Victor Brodequis<br\/><\/strong>Sciatore freeride<\/cite><\/footer><p class=\"quote-content\">\u00c8 la localit\u00e0 dove sono cresciuto e dove \u00e8 cresciuta tutta la mia famiglia. \u00c8 una localit\u00e0 iconica che non ho intenzione di lasciare per nessuna ragione al mondo. <\/p><\/blockquote><\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading is-style-title-1\">Quaderno <strong>pratico<\/strong><\/h2>\n\n<div class=\"wp-block-ws-library-ws-tabs alignfull\"><ul class=\"tabs-titles\"><li class=\"tab-title is-active\" data-tab-index=\"0\">Mappa del percorso<\/li><li class=\"tab-title\" data-tab-index=\"1\">Webcam<\/li><li class=\"tab-title\" data-tab-index=\"2\">Bollettino della neve<\/li><li class=\"tab-title\" data-tab-index=\"3\">Alloggio  <\/li><\/ul><div class=\"tabs-list\">\n<div class=\"wp-block-ws-library-ws-tab\" style=\"display:none\"><p class=\"tab-title\">Mappa del percorso<\/p><div class=\"tab-content\">\n<div class=\"wp-block-ws-library-ws-image tab-group-media\"><div class=\"wrapper\"><div class=\"group-media\"><a href=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/plan-des-pistes-les-orres-2025-26-complet-bd-page-0001-scaled.jpg\" data-glightbox=\"true\" class=\"lightbox-trigger\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/plan-des-pistes-les-orres-2025-26-complet-bd-page-0001-815x640.jpg\" alt=\"\" class=\"single_image ws-image-82463\"><\/a><div class=\"credits\"><\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-group tab-row is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-4ec0c7c6 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/plan-des-pistes-les-orres-2025-26-complet-bd-page-0001-scaled.jpg\">Scarica la mappa<\/a><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-tab\" style=\"display:none\"><p class=\"tab-title\">Webcam<\/p><div class=\"tab-content\">\n<div class=\"wp-block-group tab-row is-nowrap is-layout-flex wp-container-core-group-is-layout-002ffff5 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group tab-group-content is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"is-style-highlighted wp-block-paragraph\">Segui il meteo, le condizioni della neve e l&#8217;attivit\u00e0 sulle piste per pianificare la tua giornata in montagna!<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-webcam has-ws-lightbox\" aria-haspopup=\"dialog\" role=\"button\" aria-expanded=\"false\" aria-label=\"Les Orres  \u2013 sommet de Pousterle (2530m)\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"77534\" href=\"#\"><a class=\"wp-block-button__link wp-element-button has-ws-lightbox\" href=\"#\" role=\"button\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"77534\" data-ws-lightbox-snippet=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LnNraWluZm8uaXQvbGVzLW9ycmVzL3BvdXN0ZXJsZSIgd2lkdGg9IjEwMCUiIGhlaWdodD0iNDUwIiBmcmFtZWJvcmRlcj0iMCIgYWxsb3dmdWxsc2NyZWVuPjwvaWZyYW1lPg==\">Guarda la webcam<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-tab\" style=\"display:none\"><p class=\"tab-title\">Bollettino della neve<\/p><div class=\"tab-content\">\n<div class=\"wp-block-group tab-row is-nowrap is-layout-flex wp-container-core-group-is-layout-002ffff5 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group tab-group-content is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"is-style-highlighted wp-block-paragraph\">Scopri le condizioni della neve nel resort:<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-snow has-ws-lightbox\" aria-haspopup=\"dialog\" role=\"button\" aria-expanded=\"false\" aria-label=\"BULLETIN NEIGE \u2013 Les Orres\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"82879\" href=\"#\"><a class=\"wp-block-button__link wp-element-button has-ws-lightbox\" href=\"#\" role=\"button\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-ws-lightbox=\"true\" data-ws-lightbox-webcam=\"82879\" data-ws-lightbox-snippet=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LnNraWluZm8uaXQvd2lkZ2V0L3Nub3c\/cmVzb3J0PTIxMDQiIHdpZHRoPSIxMDAlIiBoZWlnaHQ9IjQ1MCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj48L2lmcmFtZT4=\">Vedi il bollettino della neve<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-tab\" style=\"display:none\"><p class=\"tab-title\">Alloggio  <\/p><div class=\"tab-content\">\n<div class=\"wp-block-group tab-row is-nowrap is-layout-flex wp-container-core-group-is-layout-002ffff5 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group tab-group-content is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"is-style-highlighted wp-block-paragraph\">Stai cercando una vacanza a Les Orres? Trova il tuo alloggio e tutti i servizi di cui hai bisogno. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-image tab-group-media\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.hautes-alpes.net\/it\/come-organizzarsi\/alloggi-ammobiliati-e-gites\/?_station=les-orres-1849-fr\">Vedi l&#8217;alloggio<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Hai bisogno di un consiglio?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&#8217;ufficio turistico,<br\/><strong>\u00e8 il tuo alleato locale<\/strong>.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Buoni suggerimenti, idee per attivit\u00e0, consigli personalizzati: <\/strong>non esitare a venire a conoscere o a contattare <strong>i team<\/strong> dell&#8217;Ufficio del Turismo per sfruttare al meglio la tua destinazione.<\/p>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">Les Orres<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">1 Place Des \u00c9toiles 05200, Les Orres 1650<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><a href=\"tel:+33492249898\">04 92 44 01 61<\/a><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill is-style-default\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/www.lesorres.com\" target=\"_blank\" rel=\"noreferrer noopener\">Sito web dell&#8217;ufficio<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-default\"\/>\n\n<h2 class=\"wp-block-heading is-style-title-1\"><strong>Vedi anche<\/strong><\/h2>\n\n<div class=\"wp-block-group alignwide list-nodetails is-content-justification-center is-layout-flex wp-container-core-group-is-layout-c9a5442e wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-image is-style-simple\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/serre-poncon-28-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-53667\"><div class=\"credits\">Ufficio del Turismo di Serre-Pon\u00e7on<\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-title-2\"><em>Destinazioni<br\/><\/em>Serre-Pon\u00e7on<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/serre-poncon\/\">Vedi<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-image is-style-simple\"><div class=\"wrapper\"><div class=\"group-media\"><img decoding=\"async\" src=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/thibaut-blais-23-1240x800.jpg\" alt=\"\" class=\"single_image ws-image-85311\"><div class=\"credits\"><\/div><\/div><p class=\"caption\"><\/p><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-title-2\"><em>Esperienze in mountain bike<\/em><\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.hautes-alpes.net\/it\/esperienze-hautes-alpes\/bicicletta-da-montagna\/\">Vedi<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-ws-library-ws-share\"><span class=\"share-subtitle\">Ti \u00e8 piaciuta questa pagina?<\/span><span class=\"share-title\">Condividilo!<\/span><button class=\"ws-share-button wp-element-button\">Condividi questa pagina<\/button><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La montagna di domani Arroccato sopra il lago di Serre-Pon\u00e7on, Les Orres \u00e8 un vero e proprio parco giochi a [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":107584,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"is_dark_mode":false,"footnotes":""},"page_label":[],"class_list":["post-108316","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Orres - Hautes-Alpes<\/title>\n<meta name=\"description\" content=\"Les Orres La montagna di domani Arroccato sopra il lago di Serre-Pon\u00e7on, Les Orres \u00e8 un vero e proprio parco giochi a grandezza naturale. Ogni pista \u00e8 un\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Orres - Hautes-Alpes\" \/>\n<meta property=\"og:description\" content=\"Les Orres La montagna di domani Arroccato sopra il lago di Serre-Pon\u00e7on, Les Orres \u00e8 un vero e proprio parco giochi a grandezza naturale. Ogni pista \u00e8 un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T08:22:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/itinera-magica-les-orres-24-2000x1000.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/les-orres\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/les-orres\\\/\",\"name\":\"Les Orres - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/les-orres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/les-orres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/itinera-magica-les-orres-24-2000x1000.jpg\",\"datePublished\":\"2025-11-19T15:40:35+00:00\",\"dateModified\":\"2026-06-22T08:22:10+00:00\",\"description\":\"Les Orres La montagna di domani Arroccato sopra il lago di Serre-Pon\u00e7on, Les Orres \u00e8 un vero e proprio parco giochi a grandezza naturale. Ogni pista \u00e8 un\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/les-orres\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/les-orres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/les-orres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/itinera-magica-les-orres-24-2000x1000.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/itinera-magica-les-orres-24-2000x1000.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/les-orres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destinazioni - Hautes-Alpes\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Destinazioni - Hautes-Alpes\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/destinazioni-hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Les Orres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Orres - Hautes-Alpes","description":"Les Orres La montagna di domani Arroccato sopra il lago di Serre-Pon\u00e7on, Les Orres \u00e8 un vero e proprio parco giochi a grandezza naturale. Ogni pista \u00e8 un","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/","og_locale":"it_IT","og_type":"article","og_title":"Les Orres - Hautes-Alpes","og_description":"Les Orres La montagna di domani Arroccato sopra il lago di Serre-Pon\u00e7on, Les Orres \u00e8 un vero e proprio parco giochi a grandezza naturale. Ogni pista \u00e8 un","og_url":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/","og_site_name":"Hautes-Alpes","article_modified_time":"2026-06-22T08:22:10+00:00","og_image":[{"url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/itinera-magica-les-orres-24-2000x1000.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/","url":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/","name":"Les Orres - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/#primaryimage"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/itinera-magica-les-orres-24-2000x1000.jpg","datePublished":"2025-11-19T15:40:35+00:00","dateModified":"2026-06-22T08:22:10+00:00","description":"Les Orres La montagna di domani Arroccato sopra il lago di Serre-Pon\u00e7on, Les Orres \u00e8 un vero e proprio parco giochi a grandezza naturale. Ogni pista \u00e8 un","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/#primaryimage","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/itinera-magica-les-orres-24-2000x1000.jpg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2025\/11\/itinera-magica-les-orres-24-2000x1000.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/les-orres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/it\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Destinazioni - Hautes-Alpes","item":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/"},{"@type":"ListItem","position":3,"name":"Destinazioni - Hautes-Alpes","item":"https:\/\/www.hautes-alpes.net\/it\/destinazioni-hautes-alpes\/"},{"@type":"ListItem","position":4,"name":"Les Orres"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/it\/#website","url":"https:\/\/www.hautes-alpes.net\/it\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/it\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hautes-alpes.net\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/pages\/108316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/comments?post=108316"}],"version-history":[{"count":10,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/pages\/108316\/revisions"}],"predecessor-version":[{"id":620403,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/pages\/108316\/revisions\/620403"}],"up":[{"embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/pages\/107584"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/media?parent=108316"}],"wp:term":[{"taxonomy":"page_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/page_label?post=108316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}