{"id":784192,"date":"2026-08-13T17:35:27","date_gmt":"2026-08-13T15:35:27","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/eau-vive-passion-vtt-4\/"},"modified":"2026-08-13T17:35:27","modified_gmt":"2026-08-13T15:35:27","slug":"eau-vive-passion-vtt-4","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/","title":{"rendered":"Eau Vive Passion - VTT"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"4771531"},"apidae-selections":[7805,7860,7865],"apidae-environnements":[],"apidae-chaines":[],"apidae-communes":[3988],"apidae-modes_paiement":[166,188,192,1444,5948,183,174],"apidae-services":[234,4965],"apidae-natures_terrain":[],"apidae-distinctions":[8295,7965,7975,8285,8045],"apidae-langues_parlees":[201,197],"apidae-equipements":[474],"apidae-equipements_activite":[],"apidae-conforts":[],"apidae-activites":[],"apidae-tourismes_adaptes":[2098,602,1538,315,5493],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[325,1395,3601,330,320],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[3620],"apidae-activites_sportives":[3635,3650,1170,3640,3645,4885,1130],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[3625,3630],"apidae-fete_manifestation_cat":[],"apidae-criteres_internes":[],"apidae-territoires":[423,2368,419,407,399,2353,411,2348,2363],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[371,375,379,383],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[],"apidae-tourisme_affaire":[459],"class_list":["post-784192","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eau Vive Passion - VTT - Hautes-Alpes<\/title>\n<meta name=\"description\" content=\"Oltre 35 anni nel settore degli sport di montagna e del tempo libero con un team motivato ed esperto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eau Vive Passion - VTT - Hautes-Alpes\" \/>\n<meta property=\"og:description\" content=\"Oltre 35 anni nel settore degli sport di montagna e del tempo libero con un team motivato ed esperto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/eau-vive-passion-vtt-4\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/eau-vive-passion-vtt-4\\\/\",\"name\":\"Eau Vive Passion - VTT - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#website\"},\"datePublished\":\"2026-08-13T15:35:27+00:00\",\"description\":\"Oltre 35 anni nel settore degli sport di montagna e del tempo libero con un team motivato ed esperto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/eau-vive-passion-vtt-4\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/eau-vive-passion-vtt-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/eau-vive-passion-vtt-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eau Vive Passion - VTT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eau Vive Passion - VTT - Hautes-Alpes","description":"Oltre 35 anni nel settore degli sport di montagna e del tempo libero con un team motivato ed esperto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/","og_locale":"it_IT","og_type":"article","og_title":"Eau Vive Passion - VTT - Hautes-Alpes","og_description":"Oltre 35 anni nel settore degli sport di montagna e del tempo libero con un team motivato ed esperto.","og_url":"https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/","og_site_name":"Hautes-Alpes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/","url":"https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/","name":"Eau Vive Passion - VTT - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/it\/#website"},"datePublished":"2026-08-13T15:35:27+00:00","description":"Oltre 35 anni nel settore degli sport di montagna e del tempo libero con un team motivato ed esperto.","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/it\/fiche\/eau-vive-passion-vtt-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/it\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Eau Vive Passion - VTT"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/it\/#website","url":"https:\/\/www.hautes-alpes.net\/it\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/it\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hautes-alpes.net\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae\/784192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/media?parent=784192"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-selections?post=784192"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-environnements?post=784192"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-chaines?post=784192"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-communes?post=784192"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-modes_paiement?post=784192"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-services?post=784192"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-natures_terrain?post=784192"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-distinctions?post=784192"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-langues_parlees?post=784192"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-equipements?post=784192"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-equipements_activite?post=784192"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-conforts?post=784192"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-activites?post=784192"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=784192"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=784192"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_clientele?post=784192"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=784192"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=784192"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-activites_sportives?post=784192"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=784192"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=784192"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=784192"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-criteres_internes?post=784192"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-territoires?post=784192"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=784192"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-salles_equipement?post=784192"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=784192"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-salles_restauration?post=784192"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-categories?post=784192"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-specialites?post=784192"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-indications_periode?post=784192"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_label?post=784192"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-hotel_classement?post=784192"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_hebergement?post=784192"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=784192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}