{"id":689707,"date":"2026-07-16T22:28:22","date_gmt":"2026-07-16T20:28:22","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/rifugio-terzo-alpini\/"},"modified":"2026-07-16T22:28:22","modified_gmt":"2026-07-16T20:28:22","slug":"rifugio-terzo-alpini","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/","title":{"rendered":"Rifugio Terzo Alpini"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"227389"},"apidae-selections":[7820],"apidae-environnements":[342],"apidae-chaines":[],"apidae-communes":[1090],"apidae-modes_paiement":[166,174],"apidae-services":[6257,275,539,535,5543,260],"apidae-natures_terrain":[],"apidae-distinctions":[],"apidae-langues_parlees":[205,197],"apidae-equipements":[1250,494,499,872,3449,209,217],"apidae-equipements_activite":[],"apidae-conforts":[761,6262,3824],"apidae-activites":[],"apidae-tourismes_adaptes":[],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[],"apidae-criteres_internes":[],"apidae-territoires":[423,1100,403,419,971,435,427,407,1105,411],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[375,379,383],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[5548],"apidae-tourisme_affaire":[459],"class_list":["post-689707","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rifugio Terzo Alpini - Hautes-Alpes<\/title>\n<meta name=\"description\" content=\"Il Terzo Alpini \u00e8 un rifugio situato nella Vall\u00e9e Etroite, a 1780 m di altitudine. La Vall\u00e9e Etroite fa parte del comune di N\u00e9vache ed \u00e8 un sito classificato e protetto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rifugio Terzo Alpini - Hautes-Alpes\" \/>\n<meta property=\"og:description\" content=\"Il Terzo Alpini \u00e8 un rifugio situato nella Vall\u00e9e Etroite, a 1780 m di altitudine. La Vall\u00e9e Etroite fa parte del comune di N\u00e9vache ed \u00e8 un sito classificato e protetto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/rifugio-terzo-alpini\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/rifugio-terzo-alpini\\\/\",\"name\":\"Rifugio Terzo Alpini - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#website\"},\"datePublished\":\"2026-07-16T20:28:22+00:00\",\"description\":\"Il Terzo Alpini \u00e8 un rifugio situato nella Vall\u00e9e Etroite, a 1780 m di altitudine. La Vall\u00e9e Etroite fa parte del comune di N\u00e9vache ed \u00e8 un sito classificato e protetto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/rifugio-terzo-alpini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/rifugio-terzo-alpini\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/fiche\\\/rifugio-terzo-alpini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rifugio Terzo Alpini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rifugio Terzo Alpini - Hautes-Alpes","description":"Il Terzo Alpini \u00e8 un rifugio situato nella Vall\u00e9e Etroite, a 1780 m di altitudine. La Vall\u00e9e Etroite fa parte del comune di N\u00e9vache ed \u00e8 un sito classificato e protetto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/","og_locale":"it_IT","og_type":"article","og_title":"Rifugio Terzo Alpini - Hautes-Alpes","og_description":"Il Terzo Alpini \u00e8 un rifugio situato nella Vall\u00e9e Etroite, a 1780 m di altitudine. La Vall\u00e9e Etroite fa parte del comune di N\u00e9vache ed \u00e8 un sito classificato e protetto.","og_url":"https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/","og_site_name":"Hautes-Alpes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/","url":"https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/","name":"Rifugio Terzo Alpini - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/it\/#website"},"datePublished":"2026-07-16T20:28:22+00:00","description":"Il Terzo Alpini \u00e8 un rifugio situato nella Vall\u00e9e Etroite, a 1780 m di altitudine. La Vall\u00e9e Etroite fa parte del comune di N\u00e9vache ed \u00e8 un sito classificato e protetto.","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/it\/fiche\/rifugio-terzo-alpini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/it\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Rifugio Terzo Alpini"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/it\/#website","url":"https:\/\/www.hautes-alpes.net\/it\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/it\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hautes-alpes.net\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae\/689707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/media?parent=689707"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-selections?post=689707"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-environnements?post=689707"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-chaines?post=689707"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-communes?post=689707"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-modes_paiement?post=689707"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-services?post=689707"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-natures_terrain?post=689707"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-distinctions?post=689707"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-langues_parlees?post=689707"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-equipements?post=689707"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-equipements_activite?post=689707"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-conforts?post=689707"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-activites?post=689707"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=689707"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=689707"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_clientele?post=689707"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=689707"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=689707"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-activites_sportives?post=689707"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=689707"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=689707"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=689707"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-criteres_internes?post=689707"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-territoires?post=689707"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=689707"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-salles_equipement?post=689707"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=689707"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-salles_restauration?post=689707"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-categories?post=689707"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-specialites?post=689707"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-indications_periode?post=689707"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_label?post=689707"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-hotel_classement?post=689707"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-types_hebergement?post=689707"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/it\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=689707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}