{"id":852272,"date":"2026-09-01T14:40:09","date_gmt":"2026-09-01T12:40:09","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/pachamama-festival-5-4\/"},"modified":"2026-09-01T14:40:09","modified_gmt":"2026-09-01T12:40:09","slug":"pachamama-festival-5-4","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/","title":{"rendered":"Pachamama Festival #5"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"7481318"},"apidae-selections":[11113,11114],"apidae-environnements":[],"apidae-chaines":[],"apidae-communes":[10290],"apidae-modes_paiement":[],"apidae-services":[9500],"apidae-natures_terrain":[],"apidae-distinctions":[],"apidae-langues_parlees":[9371],"apidae-equipements":[],"apidae-equipements_activite":[],"apidae-conforts":[],"apidae-activites":[],"apidae-tourismes_adaptes":[9691,9512,9698],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[11138,11136,11129],"apidae-criteres_internes":[],"apidae-territoires":[9471,9647,9715,9470,9467,9717,9650,9714,9468,10069,9716,9921,9713],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[9517],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[],"apidae-tourisme_affaire":[],"class_list":["post-852272","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pachamama Festival #5 - Hautes-Alpes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pachamama Festival #5 - Hautes-Alpes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pachamama-festival-5-4\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pachamama-festival-5-4\\\/\",\"name\":\"Pachamama Festival #5 - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#website\"},\"datePublished\":\"2026-09-01T12:40:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pachamama-festival-5-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pachamama-festival-5-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pachamama-festival-5-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/altos-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pachamama Festival #5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pachamama Festival #5 - Hautes-Alpes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/","og_locale":"es_ES","og_type":"article","og_title":"Pachamama Festival #5 - Hautes-Alpes","og_url":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/","og_site_name":"Hautes-Alpes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/","url":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/","name":"Pachamama Festival #5 - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/es\/#website"},"datePublished":"2026-09-01T12:40:09+00:00","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pachamama-festival-5-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/es\/altos-alpes\/"},{"@type":"ListItem","position":2,"name":"Pachamama Festival #5"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/es\/#website","url":"https:\/\/www.hautes-alpes.net\/es\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/es\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hautes-alpes.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae\/852272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/media?parent=852272"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-selections?post=852272"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-environnements?post=852272"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-chaines?post=852272"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-communes?post=852272"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-modes_paiement?post=852272"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-services?post=852272"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-natures_terrain?post=852272"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-distinctions?post=852272"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-langues_parlees?post=852272"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-equipements?post=852272"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-equipements_activite?post=852272"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-conforts?post=852272"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-activites?post=852272"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=852272"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=852272"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_clientele?post=852272"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=852272"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=852272"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-activites_sportives?post=852272"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=852272"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=852272"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=852272"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-criteres_internes?post=852272"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-territoires?post=852272"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=852272"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-salles_equipement?post=852272"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=852272"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-salles_restauration?post=852272"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-categories?post=852272"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-specialites?post=852272"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-indications_periode?post=852272"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_label?post=852272"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-hotel_classement?post=852272"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_hebergement?post=852272"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=852272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}