{"id":850364,"date":"2026-09-01T00:33:10","date_gmt":"2026-08-31T22:33:10","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/"},"modified":"2026-09-01T00:33:10","modified_gmt":"2026-08-31T22:33:10","slug":"pendolas-perchees-du-camping-la-cabane-4","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/","title":{"rendered":"Pendolas perch\u00e9es du camping la Cabane"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"5419940"},"apidae-selections":[9971],"apidae-environnements":[9447,9446,9444],"apidae-chaines":[],"apidae-communes":[10101],"apidae-modes_paiement":[9487,9486,9366,9365],"apidae-services":[9500,9632,9502],"apidae-natures_terrain":[],"apidae-distinctions":[9456],"apidae-langues_parlees":[9370],"apidae-equipements":[9379,9392,9372,9391,9976,10015,9374,9499],"apidae-equipements_activite":[],"apidae-conforts":[10104,10094],"apidae-activites":[],"apidae-tourismes_adaptes":[],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[],"apidae-criteres_internes":[],"apidae-territoires":[9471,9824,9470,9821,9823,9467,9468,9572],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[9517,9452,9451],"apidae-types_label":[],"apidae-hotel_classement":[9547],"apidae-types_hebergement":[9987],"apidae-tourisme_affaire":[9479],"class_list":["post-850364","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pendolas perch\u00e9es du camping la Cabane - Hautes-Alpes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pendolas perch\u00e9es du camping la Cabane - Hautes-Alpes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pendolas-perchees-du-camping-la-cabane-4\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pendolas-perchees-du-camping-la-cabane-4\\\/\",\"name\":\"Pendolas perch\u00e9es du camping la Cabane - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#website\"},\"datePublished\":\"2026-08-31T22:33:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pendolas-perchees-du-camping-la-cabane-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pendolas-perchees-du-camping-la-cabane-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/fiche\\\/pendolas-perchees-du-camping-la-cabane-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/altos-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pendolas perch\u00e9es du camping la Cabane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pendolas perch\u00e9es du camping la Cabane - Hautes-Alpes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/","og_locale":"es_ES","og_type":"article","og_title":"Pendolas perch\u00e9es du camping la Cabane - Hautes-Alpes","og_url":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/","og_site_name":"Hautes-Alpes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/","url":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/","name":"Pendolas perch\u00e9es du camping la Cabane - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/es\/#website"},"datePublished":"2026-08-31T22:33:10+00:00","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/es\/fiche\/pendolas-perchees-du-camping-la-cabane-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/es\/altos-alpes\/"},{"@type":"ListItem","position":2,"name":"Pendolas perch\u00e9es du camping la Cabane"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/es\/#website","url":"https:\/\/www.hautes-alpes.net\/es\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/es\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hautes-alpes.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae\/850364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/media?parent=850364"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-selections?post=850364"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-environnements?post=850364"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-chaines?post=850364"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-communes?post=850364"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-modes_paiement?post=850364"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-services?post=850364"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-natures_terrain?post=850364"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-distinctions?post=850364"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-langues_parlees?post=850364"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-equipements?post=850364"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-equipements_activite?post=850364"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-conforts?post=850364"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-activites?post=850364"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=850364"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=850364"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_clientele?post=850364"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=850364"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=850364"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-activites_sportives?post=850364"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=850364"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=850364"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=850364"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-criteres_internes?post=850364"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-territoires?post=850364"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=850364"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-salles_equipement?post=850364"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=850364"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-salles_restauration?post=850364"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-categories?post=850364"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-specialites?post=850364"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-indications_periode?post=850364"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_label?post=850364"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-hotel_classement?post=850364"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-types_hebergement?post=850364"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/es\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=850364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}