{"id":855005,"date":"2026-09-02T03:14:20","date_gmt":"2026-09-02T01:14:20","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/camping-de-chanterane-3\/"},"modified":"2026-09-02T03:14:20","modified_gmt":"2026-09-02T01:14:20","slug":"camping-de-chanterane-3","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/","title":{"rendered":"Camping de Chanterane"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"226504"},"apidae-selections":[7878],"apidae-environnements":[356,332,340,336,906,779,360,778],"apidae-chaines":[],"apidae-communes":[2268],"apidae-modes_paiement":[172,164],"apidae-services":[3797,2511,1467,232,3089,246],"apidae-natures_terrain":[],"apidae-distinctions":[7941],"apidae-langues_parlees":[],"apidae-equipements":[866,470,4643,2506,815,3397,1248,3782,1272],"apidae-equipements_activite":[],"apidae-conforts":[3822,2146],"apidae-activites":[],"apidae-tourismes_adaptes":[],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[],"apidae-criteres_internes":[],"apidae-territoires":[421,2057,417,969,2052,405,2071,409,2243,994,2248],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[381,373],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[2541],"apidae-tourisme_affaire":[457],"class_list":["post-855005","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camping de Chanterane - Hautes-Alpes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camping de Chanterane - Hautes-Alpes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/camping-de-chanterane-3\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/camping-de-chanterane-3\\\/\",\"name\":\"Camping de Chanterane - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#website\"},\"datePublished\":\"2026-09-02T01:14:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/camping-de-chanterane-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/camping-de-chanterane-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/camping-de-chanterane-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camping de Chanterane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camping de Chanterane - Hautes-Alpes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/","og_locale":"en_US","og_type":"article","og_title":"Camping de Chanterane - Hautes-Alpes","og_url":"https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/","og_site_name":"Hautes-Alpes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/","url":"https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/","name":"Camping de Chanterane - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/en\/#website"},"datePublished":"2026-09-02T01:14:20+00:00","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/en\/fiche\/camping-de-chanterane-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hautes-alpes.net\/en\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Camping de Chanterane"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/en\/#website","url":"https:\/\/www.hautes-alpes.net\/en\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/en\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hautes-alpes.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae\/855005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/media?parent=855005"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-selections?post=855005"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-environnements?post=855005"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-chaines?post=855005"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-communes?post=855005"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-modes_paiement?post=855005"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-services?post=855005"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-natures_terrain?post=855005"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-distinctions?post=855005"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-langues_parlees?post=855005"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-equipements?post=855005"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-equipements_activite?post=855005"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-conforts?post=855005"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-activites?post=855005"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=855005"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=855005"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_clientele?post=855005"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=855005"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=855005"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-activites_sportives?post=855005"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=855005"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=855005"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=855005"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-criteres_internes?post=855005"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-territoires?post=855005"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=855005"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-salles_equipement?post=855005"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=855005"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-salles_restauration?post=855005"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-categories?post=855005"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-specialites?post=855005"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-indications_periode?post=855005"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_label?post=855005"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-hotel_classement?post=855005"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_hebergement?post=855005"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=855005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}