{"id":851887,"date":"2026-09-01T04:35:12","date_gmt":"2026-09-01T02:35:12","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/"},"modified":"2026-09-01T04:35:12","modified_gmt":"2026-09-01T02:35:12","slug":"journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/","title":{"rendered":"Journ\u00e9es Europ\u00e9ennes du Patrimoine &#8211; Lecture: &#8220;Capturer l&#8217;invisible&#8221;"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"7516806"},"apidae-selections":[7848,8644],"apidae-environnements":[],"apidae-chaines":[],"apidae-communes":[941],"apidae-modes_paiement":[],"apidae-services":[],"apidae-natures_terrain":[],"apidae-distinctions":[],"apidae-langues_parlees":[203],"apidae-equipements":[],"apidae-equipements_activite":[],"apidae-conforts":[],"apidae-activites":[],"apidae-tourismes_adaptes":[],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[4998],"apidae-criteres_internes":[],"apidae-territoires":[421,974,401,417,969,405,409,994,790,979,989,984],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[1075,373],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[],"apidae-tourisme_affaire":[],"class_list":["post-851887","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journ\u00e9es Europ\u00e9ennes du Patrimoine - Lecture: &quot;Capturer l&#039;invisible&quot; - Hautes-Alpes<\/title>\n<meta name=\"description\" content=\"Reading \u2013 \u201cCapturing the Invisible\u201d by the El Pudu Theatre Company\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journ\u00e9es Europ\u00e9ennes du Patrimoine - Lecture: &quot;Capturer l&#039;invisible&quot; - Hautes-Alpes\" \/>\n<meta property=\"og:description\" content=\"Reading \u2013 \u201cCapturing the Invisible\u201d by the El Pudu Theatre Company\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\\\/\",\"name\":\"Journ\u00e9es Europ\u00e9ennes du Patrimoine - Lecture: \\\"Capturer l'invisible\\\" - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#website\"},\"datePublished\":\"2026-09-01T02:35:12+00:00\",\"description\":\"Reading \u2013 \u201cCapturing the Invisible\u201d by the El Pudu Theatre Company\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/fiche\\\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journ\u00e9es Europ\u00e9ennes du Patrimoine - Lecture: \u00a0\u00bbCapturer l&rsquo;invisible\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journ\u00e9es Europ\u00e9ennes du Patrimoine - Lecture: \"Capturer l'invisible\" - Hautes-Alpes","description":"Reading \u2013 \u201cCapturing the Invisible\u201d by the El Pudu Theatre Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/","og_locale":"en_US","og_type":"article","og_title":"Journ\u00e9es Europ\u00e9ennes du Patrimoine - Lecture: \"Capturer l'invisible\" - Hautes-Alpes","og_description":"Reading \u2013 \u201cCapturing the Invisible\u201d by the El Pudu Theatre Company","og_url":"https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/","og_site_name":"Hautes-Alpes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/","url":"https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/","name":"Journ\u00e9es Europ\u00e9ennes du Patrimoine - Lecture: \"Capturer l'invisible\" - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/en\/#website"},"datePublished":"2026-09-01T02:35:12+00:00","description":"Reading \u2013 \u201cCapturing the Invisible\u201d by the El Pudu Theatre Company","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/en\/fiche\/journees-europeennes-du-patrimoine-lecture-capturer-linvisible-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hautes-alpes.net\/en\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Journ\u00e9es Europ\u00e9ennes du Patrimoine - Lecture: \u00a0\u00bbCapturer l&rsquo;invisible\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/en\/#website","url":"https:\/\/www.hautes-alpes.net\/en\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/en\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hautes-alpes.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae\/851887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/media?parent=851887"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-selections?post=851887"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-environnements?post=851887"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-chaines?post=851887"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-communes?post=851887"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-modes_paiement?post=851887"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-services?post=851887"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-natures_terrain?post=851887"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-distinctions?post=851887"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-langues_parlees?post=851887"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-equipements?post=851887"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-equipements_activite?post=851887"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-conforts?post=851887"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-activites?post=851887"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=851887"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=851887"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_clientele?post=851887"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=851887"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=851887"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-activites_sportives?post=851887"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=851887"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=851887"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=851887"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-criteres_internes?post=851887"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-territoires?post=851887"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=851887"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-salles_equipement?post=851887"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=851887"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-salles_restauration?post=851887"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-categories?post=851887"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-specialites?post=851887"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-indications_periode?post=851887"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_label?post=851887"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-hotel_classement?post=851887"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-types_hebergement?post=851887"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/en\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=851887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}