{"id":577491,"date":"2026-06-03T13:18:21","date_gmt":"2026-06-03T11:18:21","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/"},"modified":"2026-06-03T13:18:21","modified_gmt":"2026-06-03T11:18:21","slug":"journees-portes-ouvertes-au-musee-lestanco-2","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/","title":{"rendered":"Journ\u00e9es portes ouvertes au Mus\u00e9e L&#8217;Estanco"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"6615588"},"apidae-selections":[7849,8645],"apidae-environnements":[],"apidae-chaines":[],"apidae-communes":[2925],"apidae-modes_paiement":[],"apidae-services":[],"apidae-natures_terrain":[],"apidae-distinctions":[],"apidae-langues_parlees":[204],"apidae-equipements":[],"apidae-equipements_activite":[],"apidae-conforts":[],"apidae-activites":[],"apidae-tourismes_adaptes":[],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[5104],"apidae-criteres_internes":[],"apidae-territoires":[422,2950,418,406,2960,2945,410,2935,2955,2940],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[374],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[],"apidae-tourisme_affaire":[],"class_list":["post-577491","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journ\u00e9es portes ouvertes au Mus\u00e9e L&#039;Estanco - Hautes-Alpes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journ\u00e9es portes ouvertes au Mus\u00e9e L&#039;Estanco - Hautes-Alpes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/journees-portes-ouvertes-au-musee-lestanco-2\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/journees-portes-ouvertes-au-musee-lestanco-2\\\/\",\"name\":\"Journ\u00e9es portes ouvertes au Mus\u00e9e L'Estanco - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#website\"},\"datePublished\":\"2026-06-03T11:18:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/journees-portes-ouvertes-au-musee-lestanco-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/journees-portes-ouvertes-au-musee-lestanco-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/journees-portes-ouvertes-au-musee-lestanco-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journ\u00e9es portes ouvertes au Mus\u00e9e L&rsquo;Estanco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journ\u00e9es portes ouvertes au Mus\u00e9e L'Estanco - Hautes-Alpes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/","og_locale":"de_DE","og_type":"article","og_title":"Journ\u00e9es portes ouvertes au Mus\u00e9e L'Estanco - Hautes-Alpes","og_url":"https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/","og_site_name":"Hautes-Alpes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/","url":"https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/","name":"Journ\u00e9es portes ouvertes au Mus\u00e9e L'Estanco - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/de\/#website"},"datePublished":"2026-06-03T11:18:21+00:00","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/de\/fiche\/journees-portes-ouvertes-au-musee-lestanco-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/de\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Journ\u00e9es portes ouvertes au Mus\u00e9e L&rsquo;Estanco"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/de\/#website","url":"https:\/\/www.hautes-alpes.net\/de\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/de\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hautes-alpes.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae\/577491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/media?parent=577491"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-selections?post=577491"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-environnements?post=577491"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-chaines?post=577491"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-communes?post=577491"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-modes_paiement?post=577491"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-services?post=577491"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-natures_terrain?post=577491"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-distinctions?post=577491"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-langues_parlees?post=577491"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-equipements?post=577491"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-equipements_activite?post=577491"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-conforts?post=577491"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-activites?post=577491"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=577491"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=577491"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_clientele?post=577491"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=577491"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=577491"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-activites_sportives?post=577491"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=577491"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=577491"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=577491"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-criteres_internes?post=577491"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-territoires?post=577491"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=577491"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-salles_equipement?post=577491"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=577491"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-salles_restauration?post=577491"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-categories?post=577491"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-specialites?post=577491"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-indications_periode?post=577491"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_label?post=577491"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-hotel_classement?post=577491"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_hebergement?post=577491"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=577491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}