{"id":523116,"date":"2026-05-13T10:27:14","date_gmt":"2026-05-13T08:27:14","guid":{"rendered":"https:\/\/www.hautes-alpes.net\/fiche\/pure-flow-munz-floor-4\/"},"modified":"2026-05-13T10:29:42","modified_gmt":"2026-05-13T08:29:42","slug":"pure-flow-munz-floor-4","status":"publish","type":"apidae","link":"https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/","title":{"rendered":"Pure Flow: Munz Floor"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"is_dark_mode":false,"idApidae":"7808271"},"apidae-selections":[7849,8645],"apidae-environnements":[341],"apidae-chaines":[],"apidae-communes":[4098],"apidae-modes_paiement":[173,165],"apidae-services":[1723],"apidae-natures_terrain":[],"apidae-distinctions":[],"apidae-langues_parlees":[204],"apidae-equipements":[5862,212],"apidae-equipements_activite":[],"apidae-conforts":[],"apidae-activites":[],"apidae-tourismes_adaptes":[],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-activites_culturelles":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[4994],"apidae-criteres_internes":[],"apidae-territoires":[422,2367,418,406,4103,2352,410,2347,975,1703],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[374],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[],"apidae-tourisme_affaire":[],"class_list":["post-523116","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pure Flow: Munz Floor - Hautes-Alpes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pure Flow: Munz Floor - Hautes-Alpes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Hautes-Alpes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T08:29:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/pure-flow-munz-floor-4\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/pure-flow-munz-floor-4\\\/\",\"name\":\"Pure Flow: Munz Floor - Hautes-Alpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#website\"},\"datePublished\":\"2026-05-13T08:27:14+00:00\",\"dateModified\":\"2026-05-13T08:29:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/pure-flow-munz-floor-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/pure-flow-munz-floor-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/fiche\\\/pure-flow-munz-floor-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/hautes-alpes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pure Flow: Munz Floor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/\",\"name\":\"ADDET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#organization\",\"name\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/www.hautes-alpes.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/black-logo-2.svg\",\"caption\":\"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hautes-alpes.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pure Flow: Munz Floor - Hautes-Alpes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/","og_locale":"de_DE","og_type":"article","og_title":"Pure Flow: Munz Floor - Hautes-Alpes","og_url":"https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/","og_site_name":"Hautes-Alpes","article_modified_time":"2026-05-13T08:29:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/","url":"https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/","name":"Pure Flow: Munz Floor - Hautes-Alpes","isPartOf":{"@id":"https:\/\/www.hautes-alpes.net\/de\/#website"},"datePublished":"2026-05-13T08:27:14+00:00","dateModified":"2026-05-13T08:29:42+00:00","breadcrumb":{"@id":"https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hautes-alpes.net\/de\/fiche\/pure-flow-munz-floor-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hautes-alpes.net\/de\/hautes-alpes\/"},{"@type":"ListItem","position":2,"name":"Pure Flow: Munz Floor"}]},{"@type":"WebSite","@id":"https:\/\/www.hautes-alpes.net\/de\/#website","url":"https:\/\/www.hautes-alpes.net\/de\/","name":"ADDET","description":"","publisher":{"@id":"https:\/\/www.hautes-alpes.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hautes-alpes.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.hautes-alpes.net\/de\/#organization","name":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes","url":"https:\/\/www.hautes-alpes.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hautes-alpes.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","contentUrl":"https:\/\/www.hautes-alpes.net\/wp-content\/uploads\/2026\/01\/black-logo-2.svg","caption":"Agence D\u00e9partementale de D\u00e9veloppement Economique et Touristique des Hautes-Alpes"},"image":{"@id":"https:\/\/www.hautes-alpes.net\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae\/523116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/media?parent=523116"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-selections?post=523116"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-environnements?post=523116"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-chaines?post=523116"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-communes?post=523116"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-modes_paiement?post=523116"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-services?post=523116"},{"taxonomy":"apidae-natures_terrain","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-natures_terrain?post=523116"},{"taxonomy":"apidae-distinctions","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-distinctions?post=523116"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-langues_parlees?post=523116"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-equipements?post=523116"},{"taxonomy":"apidae-equipements_activite","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-equipements_activite?post=523116"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-conforts?post=523116"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-activites?post=523116"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=523116"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=523116"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_clientele?post=523116"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=523116"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=523116"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-activites_sportives?post=523116"},{"taxonomy":"apidae-activites_culturelles","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-activites_culturelles?post=523116"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=523116"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=523116"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-criteres_internes?post=523116"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-territoires?post=523116"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=523116"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-salles_equipement?post=523116"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=523116"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-salles_restauration?post=523116"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-categories?post=523116"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-specialites?post=523116"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-indications_periode?post=523116"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_label?post=523116"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-hotel_classement?post=523116"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-types_hebergement?post=523116"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.hautes-alpes.net\/de\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=523116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}